{"id":31831,"date":"2026-09-01T22:45:00","date_gmt":"2026-09-01T22:45:00","guid":{"rendered":"https:\/\/norceca.info\/?p=31831"},"modified":"2026-09-02T21:28:27","modified_gmt":"2026-09-02T21:28:27","slug":"mexico-sets-the-pace-with-strong-offense-against-nicaragua","status":"publish","type":"post","link":"https:\/\/norceca.info\/es\/mexico-sets-the-pace-with-strong-offense-against-nicaragua\/","title":{"rendered":"M\u00e9xico impone su ofensiva ante Nicaragua en su debut"},"content":{"rendered":"<p class=\"wp-block-paragraph\">MANAGUA, Nicaragua, 1 de septiembre de 2026.- M\u00e9xico se impuso 3-0 (25-15, 25-8, 25-21) a Nicaragua en el \u00faltimo encuentro de la primera jornada de la Copa Panamericana NORCECA Femenina Sub-23.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicaragua logr\u00f3 mantenerse cerca durante la primera mitad del set inicial, cuando M\u00e9xico apenas ten\u00eda tres puntos de ventaja (11-8). A partir de all\u00ed, las mexicanas comenzaron a marcar diferencia con su juego ofensivo, especialmente por medio de Michelle Lizarraga y Aime Topete, para llevarse el parcial 25-15.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico domin\u00f3 ampliamente el segundo set. Con Lizarraga liderando la ofensiva con nueve puntos en el parcial y aprovechando las dificultades de Nicaragua en la recepci\u00f3n, las mexicanas construyeron una ventaja de 19-4 camino al 25-8.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicaragua mostr\u00f3 una mejor versi\u00f3n en el tercer set. Las anfitrionas igualaron el marcador a 14 y se mantuvieron cerca hasta el 19-20, antes de que M\u00e9xico retomara el control en la recta final. Topete fue determinante en el cierre con sus ataques para asegurar el triunfo mexicano.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/norceca.info\/wp-content\/uploads\/2026\/09\/Mexico-wins-1024x683.jpg\" alt=\"\" class=\"wp-image-31833\" srcset=\"https:\/\/norceca.info\/wp-content\/uploads\/2026\/09\/Mexico-wins-1024x683.jpg 1024w, https:\/\/norceca.info\/wp-content\/uploads\/2026\/09\/Mexico-wins-300x200.jpg 300w, https:\/\/norceca.info\/wp-content\/uploads\/2026\/09\/Mexico-wins-768x512.jpg 768w, https:\/\/norceca.info\/wp-content\/uploads\/2026\/09\/Mexico-wins-1536x1024.jpg 1536w, https:\/\/norceca.info\/wp-content\/uploads\/2026\/09\/Mexico-wins-18x12.jpg 18w, https:\/\/norceca.info\/wp-content\/uploads\/2026\/09\/Mexico-wins-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">M\u00e9xico wins<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Topete encabez\u00f3 a M\u00e9xico con 16 puntos y Lizarraga agreg\u00f3 12. Por Nicaragua, Mar\u00eda Jos\u00e9 Rivera aport\u00f3 seis puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico fue superior en ataque 51-23, en bloqueo 6-2 y en servicio 2-0. Las mexicanas recibieron 16 puntos por errores de Nicaragua y concedieron 19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico enfrentar\u00e1 a Rep\u00fablica Dominicana este mi\u00e9rcoles a las 5:00 p.m., mientras Nicaragua jugar\u00e1 ante Canad\u00e1 a las 7:00 p.m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Luis Le\u00f3n L\u00f3pez, entrenador de M\u00e9xico:<\/strong>&nbsp;\u201cSe habl\u00f3 con las muchachas y se coment\u00f3 que en este juego iba a haber oportunidad para rotar a todas, a lo mejor un set, algunas dos. Probamos los cambios posibles que vamos a ocupar durante la competencia, tratamos que el equipo estuviera en ritmo e ir corrigiendo las fallas que tuvimos el d\u00eda de hoy. Definitivamente ma\u00f1ana va a ser un partido muy complicado y con este sistema de competencia no hay margen de error; un juego puede definir estar en las medallas o no. No es como otras competencias que se puede jugar cuartos de final, semifinal y obviamente la final; aqu\u00ed todos los partidos son demasiado importantes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mar\u00eda Cruz, capitana de M\u00e9xico:<\/strong>&nbsp;\u201cFue un poco complicado al inicio acoplarnos, es un grupo completamente nuevo, pero creo que conforme fue avanzando el partido lo hicimos bien y estas situaciones son buenas para que podamos saber qu\u00e9 hacer y c\u00f3mo controlarlo. El juego se prestaba para que pudi\u00e9ramos ver en qu\u00e9 ocasiones podemos resolver, en qu\u00e9 ocasiones se pueden hacer algunas cosas y yo creo que se manej\u00f3 bastante bien. Ma\u00f1ana vamos a salir a hacer lo que sabemos, y a\u00fan mejor, m\u00e1s conectadas, m\u00e1s como grupo, y tratar de mejorar con los errores y no cometer tantos por el tema de comunicaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Claudia Noguera, entrenadora de Nicaragua:<\/strong>&nbsp;\u201cAl inicio creo que hubo un poco de nerviosismo de las muchachas, pero se les quit\u00f3 en el tercer set y logramos hacer m\u00e1s puntos porque pudimos hacer mejor las cosas, sobre todo superar el problema del recibo, que nos afect\u00f3 mucho en el segundo set. Hemos estado un poquito mejor en ese aspecto, pues las jugadoras se han comprometido con mejorar en el K1. Lo hemos hecho, siempre caemos en una rachita, pero creo que hemos avanzado bastante\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Franchesca Viera, capitana de Nicaragua:<\/strong>&nbsp;\u201cNos sentimos sumamente felices y orgullosas de nosotras, porque a pesar de que estos partidos no son nada f\u00e1ciles, tratamos de dar lo mejor y ofrecer un buen espect\u00e1culo. Al inicio est\u00e1bamos nerviosas, pero la verdad ten\u00edamos ganas de jugar y creo que podemos mejorar bastante todav\u00eda, ir sumando experiencia que nos permita tener un buen nivel de juego y aprender m\u00e1s\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>MANAGUA, Nicaragua, September 1, 2026.- Mexico defeated Nicaragua 3-0 (25-15, 25-8, 25-21) in the final match of the opening day of the NORCECA U23 Women\u2019s Pan American Cup. Nicaragua managed to stay close during the first half of the opening set, with Mexico holding only a three-point lead (11-8). From there, Mexico began to pull [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":31832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7],"tags":[395,334,20,11],"class_list":["post-31831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volleyball","tag-2026-u23-norceca-womens-panamerican-cup","tag-2026-u23-pan-american-cup","tag-norceca","tag-volleyball"],"acf":[],"_links":{"self":[{"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/posts\/31831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/comments?post=31831"}],"version-history":[{"count":1,"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/posts\/31831\/revisions"}],"predecessor-version":[{"id":31834,"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/posts\/31831\/revisions\/31834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/media\/31832"}],"wp:attachment":[{"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/media?parent=31831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/categories?post=31831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/norceca.info\/es\/wp-json\/wp\/v2\/tags?post=31831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}